{"id":525,"date":"2026-03-24T14:55:56","date_gmt":"2026-03-24T13:55:56","guid":{"rendered":"https:\/\/import.veniceredhouse.com\/apartments-in-venice\/appartamento-calmo-2-dx\/"},"modified":"2026-05-20T15:44:54","modified_gmt":"2026-05-20T13:44:54","slug":"appartamento-calmo-2-dx","status":"publish","type":"product","link":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/","title":{"rendered":"Appartamento Calmo 2 DX"},"content":{"rendered":"<p>L&#8217;edificio si sviluppa su 3 piani. Ogni piano ha 2 appartamenti identici con 2 camere da letto, 2 bagni, un soggiorno, sala da pranzo e una cucina. Tutti gli appartamenti hanno un terrazzino e un balcone. L&#8217;edificio ha anche un giardino in comune. L&#8217;edificio si trova di fronte all&#8217;hotel Excelsior sul Lungo mare Marconi e il cancello stradale si trova a 200 metri dalla spiaggia.<br \/>\nLuminosi e spaziosi, tutti gli appartamenti sono dotati di vista sul giardino, aria condizionata, internet wireless, cucina attrezzata. Gli appartamenti possono essere affittati anche per periodi mensili o stagionali ed sono l&#8217;ideale per una vacanza in famiglia al Lido. La strada parallela al Lungo mare Marconi \u00e8 Via San Sandro Gallo dove abbondano i negozi du generi alimentari e le pasticcerie. La zona \u00e8 ben servita dagli autobus per andare in qualsiasi direzione dell&#8217;isola e la zona \u00e8 estremamente tranquilla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Posizione perfetta accanto all&#8217;Excelsior Palace Hotel e a 200 metri dalla spiaggia<\/p>\n","protected":false},"featured_media":5643,"template":"","meta":{"_acf_changed":false},"amenity":[],"product_brand":[175],"product_cat":[],"product_tag":[],"class_list":["post-525","product","type-product","status-publish","has-post-thumbnail","product_brand-lido","first","instock","purchasable","product-type-simple"],"exclude_global_add_ons":false,"addons":[{"name":"Pulizie extra","type":"input_multiplier","position":0,"required":false,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":true,"price":"120","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1779115697},{"name":"Adulti","type":"input_multiplier","position":0,"required":true,"title_format":"label","default":"1","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":true,"min":"1","max":"0","options":[],"id":1776264503},{"name":"Bambini (age: 5-11)","type":"input_multiplier","position":1,"required":false,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1776264504},{"name":"Bambini (et\u00e0: 0-4)","type":"input_multiplier","position":2,"required":false,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1776264505}],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Posizione perfetta accanto all&#039;Excelsior Palace Hotel e a 200 metri dalla spiaggia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posizione perfetta accanto all&#039;Excelsior Palace Hotel e a 200 metri dalla spiaggia\" \/>\n<meta property=\"og:description\" content=\"Posizione perfetta accanto all&#039;Excelsior Palace Hotel e a 200 metri dalla spiaggia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/\" \/>\n<meta property=\"og:site_name\" content=\"Venice Red House\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T13:44:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/03\/Calmo-DX-2-Levi-Apartment_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/\",\"name\":\"Posizione perfetta accanto all'Excelsior Palace Hotel e a 200 metri dalla spiaggia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Calmo-DX-2-Levi-Apartment_02.jpg\",\"datePublished\":\"2026-03-24T13:55:56+00:00\",\"dateModified\":\"2026-05-20T13:44:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Calmo-DX-2-Levi-Apartment_02.jpg\",\"contentUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Calmo-DX-2-Levi-Apartment_02.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/appartamenti-a-venezia\\\/appartamento-calmo-2-dx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Appartamento Calmo 2 DX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/\",\"name\":\"Venice Red House\",\"description\":\"Your Home in the Heart of Venice\",\"publisher\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#organization\",\"name\":\"Venice Red House\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-red-house-company.png\",\"contentUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-red-house-company.png\",\"width\":250,\"height\":114,\"caption\":\"Venice Red House\"},\"image\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Posizione perfetta accanto all'Excelsior Palace Hotel e a 200 metri dalla spiaggia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/","og_locale":"it_IT","og_type":"article","og_title":"Posizione perfetta accanto all'Excelsior Palace Hotel e a 200 metri dalla spiaggia","og_description":"Posizione perfetta accanto all'Excelsior Palace Hotel e a 200 metri dalla spiaggia","og_url":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/","og_site_name":"Venice Red House","article_modified_time":"2026-05-20T13:44:54+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/03\/Calmo-DX-2-Levi-Apartment_02.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/","url":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/","name":"Posizione perfetta accanto all'Excelsior Palace Hotel e a 200 metri dalla spiaggia","isPartOf":{"@id":"https:\/\/veniceredhouse.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/#primaryimage"},"image":{"@id":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/#primaryimage"},"thumbnailUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/03\/Calmo-DX-2-Levi-Apartment_02.jpg","datePublished":"2026-03-24T13:55:56+00:00","dateModified":"2026-05-20T13:44:54+00:00","breadcrumb":{"@id":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/#primaryimage","url":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/03\/Calmo-DX-2-Levi-Apartment_02.jpg","contentUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/03\/Calmo-DX-2-Levi-Apartment_02.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/veniceredhouse.com\/it\/appartamenti-a-venezia\/appartamento-calmo-2-dx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veniceredhouse.com\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/veniceredhouse.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Appartamento Calmo 2 DX"}]},{"@type":"WebSite","@id":"https:\/\/veniceredhouse.com\/it\/#website","url":"https:\/\/veniceredhouse.com\/it\/","name":"Venice Red House","description":"Your Home in the Heart of Venice","publisher":{"@id":"https:\/\/veniceredhouse.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veniceredhouse.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/veniceredhouse.com\/it\/#organization","name":"Venice Red House","url":"https:\/\/veniceredhouse.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/veniceredhouse.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/07\/logo-red-house-company.png","contentUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/07\/logo-red-house-company.png","width":250,"height":114,"caption":"Venice Red House"},"image":{"@id":"https:\/\/veniceredhouse.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/product\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/media\/5643"}],"wp:attachment":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/media?parent=525"}],"wp:term":[{"taxonomy":"amenity","embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/amenity?post=525"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/product_brand?post=525"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/product_cat?post=525"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/product_tag?post=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}