{"id":195,"date":"2019-07-30T00:00:00","date_gmt":"2019-07-29T22:00:00","guid":{"rendered":"https:\/\/import.veniceredhouse.com\/2019\/07\/september-venice-film-festival-historical-boats-and-exhibitions-4\/"},"modified":"2026-04-15T12:36:48","modified_gmt":"2026-04-15T10:36:48","slug":"september-venice-film-festival-historical-boats-and-exhibitions-4","status":"publish","type":"post","link":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/","title":{"rendered":"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre"},"content":{"rendered":"\nSettembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l&#8217;acqua del mare \u00e8 perfetta per gli ultimi bagni ed il turismo diminuisce.\n\nIn questo mese avrete l&#8217;occasione di vivere alcuni degli appuntamenti pi\u00f9 importanti dell&#8217;anno: la Mostra del Cinema con il red carpet al Lido di Venezia ed incontrare le star pi\u00f9 importanti del cinema internazionale. La Regata Storica con la parata in costume in Canal Grande dove vedere il Doge e la Dogaressa sfilare nelle storiche imbarcazioni della Serenissima. A Settembre inaugura la grande mostra a Palazzo Ducale dedicata a Tintoretto, uno dei pittori pi\u00f9 importanti della pittura europea del XVI secolo.\n\nMostra del Cinema di Venezia\nRegata Storica\nTintoretto 500: la mostra a Palazzo Ducale\n<h3 class=\"red\">Mostra del Cinema di Venezia<\/h3>\nA settembre si accendono i riflettori sulla citt\u00e0 che diventa protagonista del jet set internazionale grazie al tradizionale appuntamento con la Mostra del Cinema al Lido di Venezia, quest&#8217;anno giunta alla 75a edizione.\n\nInaugurato nel 1932, il primo Festival si svolse nella Terrazza dell\u2019Hotel Excelsior al Lido di Venezia. Non erano previsti premi in quella prima edizione, ma solo la proiezione dei film che partecipavano all\u2019iniziativa, tra cui vi erano alcune pellicole che ora sono dei classici del cinema.\n\nAncora oggi il Lido diventa palcoscenico della Mostra: il Palazzo del Cinema si veste delle scenografie e del red carpet dove sfilano attori e registi, la terrazza del Casin\u00f2, allestita solo per questo evento dove gustare un aperitivo vista mare e l&#8217;elegante Hotel Excelsior, da sempre scenografia per interviste e feste esclusive.\n\nPer gli appassionati di cinema \u00e8 l&#8217;occasione per vedere in anteprima molti film e alcuni di nicchia.\nE non \u00e8 raro in questi giorni ritrovarsi a bere un Bellini vicino a una star del cinema internazionale&#8230;\n\nSito ufficiale: <a href=\"https:\/\/www.labiennale.org\">www.labiennale.org<\/a>\n\n<img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-5464 size-large\" title=\"Mostra del Cinema_01\" src=\"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2019\/07\/Mostra-del-Cinema_01-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\">\n<h3 class=\"red\">Regata Storica<\/h3>\nAppuntamento con la tradizione il 2 settembre con la Regata Storica, l&#8217;evento pi\u00f9 importante per la tradizione della voga alla veneta, una disciplina unica al mondo e praticata da secoli in Laguna.\n\nLa spettacolare regata ha inizio con il corteo storico di decine di imbarcazioni tipiche del &#8216;500 con barche colorate e gondolieri in costume che trasportano il Doge e la dogaressa in una affascinante rievocazione storica. A seguire la competizione che vede sfidarsi differenti tipologie di imbarcazioni: la regata pi\u00f9 importante vede sfidarsi ogni anno i campioni dei gondolini in una gara di velocit\u00e0 in Canal Grande il cui traguardo \u00e8 posto davanti a Palazzo di Ca&#8217; Foscari.\n\nSito ufficiale: <a href=\"https:\/\/www.regatastoricavenezia.it\/?lang=en&amp;pg=1&amp;page=1\">www.regatastoricavenezia.it<\/a>\n\n<img decoding=\"async\" class=\"aligncenter wp-image-5723 size-large\" title=\"Regata Storica_01\" src=\"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2019\/07\/Regata-Storica_01-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\">\n<h3 class=\"red\">Tintoretto 500: la mostra a Palazzo Ducale<\/h3>\nIl 7 settembre inaugurer\u00e0 la grande mostra a Palazzo Ducale dedicata a Tintoretto, artista veneziano di cui quest&#8217;anno si festeggiano i 500 anni dalla nascita.\n\nPer l&#8217;occasione i Musei Civici di Venezia e la National Gallery of Art di Washington hanno realizzato un progetto di ricerca per festeggiare uno degli artisti pi\u00f9 importanti della pittura europea del XVI secolo: 50 dipinti e 20 disegni autografi di Tintoretto, grazie a prestiti eccezionali, provenienti dai musei italiani e da quelli di Londra \u2013 la National Gallery, la Royal Collection, il Victoria and Albert Museum, la Courtauld Gallery \u2013 da Parigi, Gent, Lione, Dresda, Otterlo, Praga, Rotterdam.\n\nVenezia, Palazzo Ducale \u2013 Appartamento del Doge\ndal 7 Settembre 2018 al 6 Gennaio 2019\n\nSito ufficiale: <a href=\"https:\/\/palazzoducale.visitmuve.it\">www.palazzoducale.visitmuve.it<\/a>\n","protected":false},"excerpt":{"rendered":"<p>Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l&#8217;acqua del mare \u00e8 perfetta per gli ultimi bagni ed il turismo diminuisce. In questo mese avrete l&#8217;occasione di vivere alcuni degli appuntamenti pi\u00f9 importanti dell&#8217;anno: la Mostra del Cinema con il red carpet [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[121],"tags":[],"class_list":["post-195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-our-venice"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre | Venice Red House<\/title>\n<meta name=\"description\" content=\"Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l&#039;acqua del mare \u00e8 perfetta per\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre | Venice Red House\" \/>\n<meta property=\"og:description\" content=\"Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l&#039;acqua del mare \u00e8 perfetta per\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Venice Red House\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-29T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T10:36:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/02\/Mostra-del-Cinema_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francesco.pesce@elan42.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francesco.pesce@elan42.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/\"},\"author\":{\"name\":\"francesco.pesce@elan42.com\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#\\\/schema\\\/person\\\/0b4fa70b3c36e61c2ca34f7ff966577f\"},\"headline\":\"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre\",\"datePublished\":\"2019-07-29T22:00:00+00:00\",\"dateModified\":\"2026-04-15T10:36:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/\"},\"wordCount\":554,\"publisher\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mostra-del-Cinema_00.jpg\",\"articleSection\":[\"Our Venice\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/\",\"name\":\"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre | Venice Red House\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mostra-del-Cinema_00.jpg\",\"datePublished\":\"2019-07-29T22:00:00+00:00\",\"dateModified\":\"2026-04-15T10:36:48+00:00\",\"description\":\"Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l'acqua del mare \u00e8 perfetta per\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mostra-del-Cinema_00.jpg\",\"contentUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mostra-del-Cinema_00.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/september-venice-film-festival-historical-boats-and-exhibitions-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/\",\"name\":\"Venice Red House\",\"description\":\"Your Home in the Heart of Venice\",\"publisher\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#organization\",\"name\":\"Venice Red House\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-red-house-company.png\",\"contentUrl\":\"https:\\\/\\\/veniceredhouse.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/logo-red-house-company.png\",\"width\":250,\"height\":114,\"caption\":\"Venice Red House\"},\"image\":{\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veniceredhouse.com\\\/it\\\/#\\\/schema\\\/person\\\/0b4fa70b3c36e61c2ca34f7ff966577f\",\"name\":\"francesco.pesce@elan42.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae3dc2d9a3e460b3bce288bcf5ea90032c1c81c55edb85407c1d25636c3dacc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae3dc2d9a3e460b3bce288bcf5ea90032c1c81c55edb85407c1d25636c3dacc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fae3dc2d9a3e460b3bce288bcf5ea90032c1c81c55edb85407c1d25636c3dacc?s=96&d=mm&r=g\",\"caption\":\"francesco.pesce@elan42.com\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre | Venice Red House","description":"Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l'acqua del mare \u00e8 perfetta per","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/","og_locale":"it_IT","og_type":"article","og_title":"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre | Venice Red House","og_description":"Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l'acqua del mare \u00e8 perfetta per","og_url":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/","og_site_name":"Venice Red House","article_published_time":"2019-07-29T22:00:00+00:00","article_modified_time":"2026-04-15T10:36:48+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/02\/Mostra-del-Cinema_00.jpg","type":"image\/jpeg"}],"author":"francesco.pesce@elan42.com","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"francesco.pesce@elan42.com","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#article","isPartOf":{"@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/"},"author":{"name":"francesco.pesce@elan42.com","@id":"https:\/\/veniceredhouse.com\/it\/#\/schema\/person\/0b4fa70b3c36e61c2ca34f7ff966577f"},"headline":"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre","datePublished":"2019-07-29T22:00:00+00:00","dateModified":"2026-04-15T10:36:48+00:00","mainEntityOfPage":{"@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/"},"wordCount":554,"publisher":{"@id":"https:\/\/veniceredhouse.com\/it\/#organization"},"image":{"@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#primaryimage"},"thumbnailUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/02\/Mostra-del-Cinema_00.jpg","articleSection":["Our Venice"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/","url":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/","name":"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre | Venice Red House","isPartOf":{"@id":"https:\/\/veniceredhouse.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#primaryimage"},"image":{"@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#primaryimage"},"thumbnailUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/02\/Mostra-del-Cinema_00.jpg","datePublished":"2019-07-29T22:00:00+00:00","dateModified":"2026-04-15T10:36:48+00:00","description":"Settembre da sempre \u00e8 tra i mesi pi\u00f9 belli per visitare Venezia: le giornate sono ancora lunghe, le serate sono fresche, l'acqua del mare \u00e8 perfetta per","breadcrumb":{"@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#primaryimage","url":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/02\/Mostra-del-Cinema_00.jpg","contentUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/02\/Mostra-del-Cinema_00.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/veniceredhouse.com\/it\/september-venice-film-festival-historical-boats-and-exhibitions-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veniceredhouse.com\/it\/"},{"@type":"ListItem","position":2,"name":"Settembre: Mostra del Cinema di Venezia, imbarcazioni storiche e mostre"}]},{"@type":"WebSite","@id":"https:\/\/veniceredhouse.com\/it\/#website","url":"https:\/\/veniceredhouse.com\/it\/","name":"Venice Red House","description":"Your Home in the Heart of Venice","publisher":{"@id":"https:\/\/veniceredhouse.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veniceredhouse.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/veniceredhouse.com\/it\/#organization","name":"Venice Red House","url":"https:\/\/veniceredhouse.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/veniceredhouse.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/07\/logo-red-house-company.png","contentUrl":"https:\/\/veniceredhouse.com\/wp-content\/uploads\/2026\/07\/logo-red-house-company.png","width":250,"height":114,"caption":"Venice Red House"},"image":{"@id":"https:\/\/veniceredhouse.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/veniceredhouse.com\/it\/#\/schema\/person\/0b4fa70b3c36e61c2ca34f7ff966577f","name":"francesco.pesce@elan42.com","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fae3dc2d9a3e460b3bce288bcf5ea90032c1c81c55edb85407c1d25636c3dacc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fae3dc2d9a3e460b3bce288bcf5ea90032c1c81c55edb85407c1d25636c3dacc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fae3dc2d9a3e460b3bce288bcf5ea90032c1c81c55edb85407c1d25636c3dacc?s=96&d=mm&r=g","caption":"francesco.pesce@elan42.com"}}]}},"_links":{"self":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/posts\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":1,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/posts\/195\/revisions"}],"predecessor-version":[{"id":4198,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/posts\/195\/revisions\/4198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/media\/165"}],"wp:attachment":[{"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/media?parent=195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/categories?post=195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veniceredhouse.com\/it\/wp-json\/wp\/v2\/tags?post=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}